{"id":35572,"date":"2020-01-21T19:40:13","date_gmt":"2020-01-22T01:40:13","guid":{"rendered":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/?p=35572"},"modified":"2020-01-16T15:21:27","modified_gmt":"2020-01-16T21:21:27","slug":"intel-entrara-al-mundo-de-las-gpu-con-su-tarjeta-con-arquitectura-xe","status":"publish","type":"post","link":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/intel-entrara-al-mundo-de-las-gpu-con-su-tarjeta-con-arquitectura-xe\/","title":{"rendered":"Intel entrar\u00e1 al mundo de las GPU con su tarjeta con arquitectura Xe #ISC"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><a href=\"https:\/\/www.facebook.com\/EscatUninter\/\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.uninter.edu.mx\/ESCAT\/wp-content\/uploads\/2020\/01\/ESCAT-2-902x1024.png\" alt=\"\" class=\"wp-image-35499\" width=\"100\" height=\"113\" srcset=\"https:\/\/blogs.uninter.edu.mx\/ESCAT\/wp-content\/uploads\/2020\/01\/ESCAT-2-902x1024.png 902w, https:\/\/blogs.uninter.edu.mx\/ESCAT\/wp-content\/uploads\/2020\/01\/ESCAT-2-264x300.png 264w, https:\/\/blogs.uninter.edu.mx\/ESCAT\/wp-content\/uploads\/2020\/01\/ESCAT-2-768x872.png 768w, https:\/\/blogs.uninter.edu.mx\/ESCAT\/wp-content\/uploads\/2020\/01\/ESCAT-2.png 1787w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/a><\/figure><\/div>\n\n\n\n<p>Los esfuerzos de Intel est\u00e1n centrados en el mercado de las CPU, pero esto podr\u00eda cambiar, pues han confirmado que trabajan en su primera GPU discreta.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>No hay muchos detalles t\u00e9cnicos de esta GPU, Intel tan solo se ha limitado a decir que est\u00e1 dise\u00f1ada con su nueva arquitectura Xe. Pero algunos medios pudieron ver una demo, donde ejecut\u00f3 &#8216;Destiny 2&#8217; sin inconvenientes.<\/p>\n\n\n\n<p>De hecho la misma arquitectura Xe ser\u00e1 la encargada de los gr\u00e1ficos integrados de los nuevos chips Tiger Lake. En otra demo de un dispositivo con estos nuevos chips, se pudo ejecutar &#8216;Warframe&#8217; con rendimiento estable.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/i.blogs.es\/112f87\/intel-tiger-lake-2-min\/450_1000.jpg\" alt=\"Intel\"\/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Tiger Lake de Intel<\/h2>\n\n\n\n<p>Tiger Lake ser\u00e1 la nueva apuesta de Intel que aproveche su arquitectura de 10nm+. Seg\u00fan los benchmarks de la misma empresa tendr\u00e1 aumentos de doble d\u00edgito en rendimiento, mejoras en la Inteligencia Artificial y hasta&#8221;cuatro veces la capacidad del USB3 con el nuevo Thunderbolt 4 integrado.&#8221;<\/p>\n\n\n\n<p>Intel aprovech\u00f3 estos anuncios para confirmar los esfuerzos que est\u00e1 realizando para impulsar el mercado de los dispositivos plegables. Record\u00e1ndonos que es el que proporciona el hardware para los productos de Lenovo y Dell reci\u00e9n presentados, en concreto cuentan con un Intel Core con tecnolog\u00eda h\u00edbrida con nombre c\u00f3digo Lakefield. Mismos que llegar\u00e1n al mercado en alg\u00fan punto de 2020.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/i.blogs.es\/ec30ab\/intel-nuc-ghost-1\/450_1000.jpg\" alt=\"Intel\"\/><\/figure><\/div>\n\n\n\n<p>Tambi\u00e9n anunci\u00f3 un nuevo NUC, el m\u00e1s poderoso que ha creado a la fecha, se llama Ghost Canyon. Es una miniPC que cuenta con un procesador Core i9 (que puede actualizarse) y que podr\u00e1 montar una GPU de escritorio en su versi\u00f3n mini. Quienes han podido probarla dicen que ofrece un rendimiento s\u00f3lido en juegos como &#8216;Shadow of the Tomb Raider&#8217; con los gr\u00e1ficos al m\u00e1ximo en resoluci\u00f3n 2560 x 1440.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\">Fuente: <a href=\"https:\/\/www.xataka.com.mx\/componentes\/intel-entrara-al-mundo-gpu-discretas-su-propia-tarjeta-arquitectura-xe-nos-da-adelanto-sus-nuevos-tiger-lake\">Xataka<\/a><\/h6>\n\n\n\n<p style=\"text-align:right\"><a href=\"https:\/\/universidad.uninter.edu.mx\/carreras\/ISC\">Ingenier\u00edas en Sistemas Computacionales<\/a><\/p>\n\n\n\n<p style=\"text-align:right\" class=\"has-text-color has-vivid-cyan-blue-color\"><a href=\"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/category\/ingenieria-en-sistemas-computacionales\/\">M\u00e1s noticias sobre Ingenier\u00eda en Sistemas Computacionales&#8230;<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/uninter.edu.mx\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"154\" src=\"https:\/\/blogs.uninter.edu.mx\/ESCAT\/wp-content\/uploads\/2019\/10\/4-1024x154-1-1024x154-1024x154.png\" alt=\"\" class=\"wp-image-33610\" srcset=\"https:\/\/blogs.uninter.edu.mx\/ESCAT\/wp-content\/uploads\/2019\/10\/4-1024x154-1-1024x154.png 1024w, https:\/\/blogs.uninter.edu.mx\/ESCAT\/wp-content\/uploads\/2019\/10\/4-1024x154-1-1024x154-300x45.png 300w, https:\/\/blogs.uninter.edu.mx\/ESCAT\/wp-content\/uploads\/2019\/10\/4-1024x154-1-1024x154-768x116.png 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Los esfuerzos de Intel est\u00e1n centrados en el mercado de las CPU, pero esto podr\u00eda cambiar, pues han confirmado que trabajan en su primera GPU discreta.<\/p>\n","protected":false},"author":22,"featured_media":35573,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[5,30,17,22,24,25],"tags":[32,104,705,49,31,37],"class_list":["post-35572","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-certificaciones","category-cisco","category-ingenieria-en-sistemas-computacionales","category-ingenierias","category-maestria-en-redes-de-computadoras-y-tecnologias-web","category-microsoft","tag-escat","tag-ingenierias","tag-intel","tag-sistemas-computacionales","tag-uninter","tag-universidad-internacional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Intel entrar\u00e1 al mundo de las GPU con su tarjeta con arquitectura Xe<\/title>\r\n<meta name=\"description\" content=\"Los esfuerzos de Intel est\u00e1n centrados en el mercado de las CPU, pero esto podr\u00eda cambiar, pues han confirmado que trabajan en su primera GPU discreta.\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/intel-entrara-al-mundo-de-las-gpu-con-su-tarjeta-con-arquitectura-xe\/\" \/>\r\n<meta property=\"og:locale\" content=\"es_MX\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Intel entrar\u00e1 al mundo de las GPU con su tarjeta con arquitectura Xe\" \/>\r\n<meta property=\"og:description\" content=\"Los esfuerzos de Intel est\u00e1n centrados en el mercado de las CPU, pero esto podr\u00eda cambiar, pues han confirmado que trabajan en su primera GPU discreta.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/intel-entrara-al-mundo-de-las-gpu-con-su-tarjeta-con-arquitectura-xe\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Escuela de Ciencias, Artes y Tecnolog\u00eda\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EscatUninter\/\" \/>\r\n<meta property=\"article:published_time\" content=\"2020-01-22T01:40:13+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/blogs.uninter.edu.mx\/ESCAT\/wp-content\/uploads\/2020\/01\/1366_2000-1.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\r\n\t<meta property=\"og:image:height\" content=\"800\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"EquipoEscat\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:image\" content=\"https:\/\/blogs.uninter.edu.mx\/ESCAT\/wp-content\/uploads\/2020\/01\/1366_2000-1.jpg\" \/>\r\n<meta name=\"twitter:creator\" content=\"@EscatUninter\" \/>\r\n<meta name=\"twitter:site\" content=\"@EscatUninter\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"EquipoEscat\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/intel-entrara-al-mundo-de-las-gpu-con-su-tarjeta-con-arquitectura-xe\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/intel-entrara-al-mundo-de-las-gpu-con-su-tarjeta-con-arquitectura-xe\/\"},\"author\":{\"name\":\"EquipoEscat\",\"@id\":\"https:\/\/blogs.uninter.edu.mx\/ESCAT\/#\/schema\/person\/df7b8f33d62433cb78a2104bda02490d\"},\"headline\":\"Intel entrar\u00e1 al mundo de las GPU con su tarjeta con arquitectura Xe #ISC\",\"datePublished\":\"2020-01-22T01:40:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/intel-entrara-al-mundo-de-las-gpu-con-su-tarjeta-con-arquitectura-xe\/\"},\"wordCount\":327,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/intel-entrara-al-mundo-de-las-gpu-con-su-tarjeta-con-arquitectura-xe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blogs.uninter.edu.mx\/ESCAT\/wp-content\/uploads\/2020\/01\/1366_2000-1.jpg\",\"keywords\":[\"ESCAT\",\"Ingenier\u00edas\",\"Intel\",\"Sistemas Computacionales\",\"Uninter\",\"Universidad Internacional\"],\"articleSection\":[\"Certificaciones\",\"CISCO\",\"Ingenier\u00eda en Sistemas Computacionales\",\"Ingenier\u00edas\",\"Maestr\u00eda en Redes de Computadoras y Tecnolog\u00edas Web\",\"Microsoft\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/intel-entrara-al-mundo-de-las-gpu-con-su-tarjeta-con-arquitectura-xe\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/intel-entrara-al-mundo-de-las-gpu-con-su-tarjeta-con-arquitectura-xe\/\",\"url\":\"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/intel-entrara-al-mundo-de-las-gpu-con-su-tarjeta-con-arquitectura-xe\/\",\"name\":\"Intel entrar\u00e1 al mundo de las GPU con su tarjeta con arquitectura Xe\",\"isPartOf\":{\"@id\":\"https:\/\/blogs.uninter.edu.mx\/ESCAT\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/intel-entrara-al-mundo-de-las-gpu-con-su-tarjeta-con-arquitectura-xe\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/intel-entrara-al-mundo-de-las-gpu-con-su-tarjeta-con-arquitectura-xe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blogs.uninter.edu.mx\/ESCAT\/wp-content\/uploads\/2020\/01\/1366_2000-1.jpg\",\"datePublished\":\"2020-01-22T01:40:13+00:00\",\"author\":{\"@id\":\"https:\/\/blogs.uninter.edu.mx\/ESCAT\/#\/schema\/person\/df7b8f33d62433cb78a2104bda02490d\"},\"description\":\"Los esfuerzos de Intel est\u00e1n centrados en el mercado de las CPU, pero esto podr\u00eda cambiar, pues han confirmado que trabajan en su primera GPU discreta.\",\"breadcrumb\":{\"@id\":\"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/intel-entrara-al-mundo-de-las-gpu-con-su-tarjeta-con-arquitectura-xe\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/intel-entrara-al-mundo-de-las-gpu-con-su-tarjeta-con-arquitectura-xe\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/intel-entrara-al-mundo-de-las-gpu-con-su-tarjeta-con-arquitectura-xe\/#primaryimage\",\"url\":\"https:\/\/blogs.uninter.edu.mx\/ESCAT\/wp-content\/uploads\/2020\/01\/1366_2000-1.jpg\",\"contentUrl\":\"https:\/\/blogs.uninter.edu.mx\/ESCAT\/wp-content\/uploads\/2020\/01\/1366_2000-1.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/intel-entrara-al-mundo-de-las-gpu-con-su-tarjeta-con-arquitectura-xe\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/blogs.uninter.edu.mx\/ESCAT\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Intel entrar\u00e1 al mundo de las GPU con su tarjeta con arquitectura Xe #ISC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blogs.uninter.edu.mx\/ESCAT\/#website\",\"url\":\"https:\/\/blogs.uninter.edu.mx\/ESCAT\/\",\"name\":\"Escuela de Ciencias, Artes y Tecnolog\u00eda UNINTER\",\"description\":\"ESCAT\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blogs.uninter.edu.mx\/ESCAT\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/blogs.uninter.edu.mx\/ESCAT\/#\/schema\/person\/df7b8f33d62433cb78a2104bda02490d\",\"name\":\"EquipoEscat\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/blogs.uninter.edu.mx\/ESCAT\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d943e53cecc7e9e13c011abf6ec7475809c7d278834bde994b19ecd58034a9ff?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d943e53cecc7e9e13c011abf6ec7475809c7d278834bde994b19ecd58034a9ff?s=96&d=mm&r=g\",\"caption\":\"EquipoEscat\"},\"url\":\"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/author\/equipoescat\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Intel entrar\u00e1 al mundo de las GPU con su tarjeta con arquitectura Xe","description":"Los esfuerzos de Intel est\u00e1n centrados en el mercado de las CPU, pero esto podr\u00eda cambiar, pues han confirmado que trabajan en su primera GPU discreta.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/intel-entrara-al-mundo-de-las-gpu-con-su-tarjeta-con-arquitectura-xe\/","og_locale":"es_MX","og_type":"article","og_title":"Intel entrar\u00e1 al mundo de las GPU con su tarjeta con arquitectura Xe","og_description":"Los esfuerzos de Intel est\u00e1n centrados en el mercado de las CPU, pero esto podr\u00eda cambiar, pues han confirmado que trabajan en su primera GPU discreta.","og_url":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/intel-entrara-al-mundo-de-las-gpu-con-su-tarjeta-con-arquitectura-xe\/","og_site_name":"Escuela de Ciencias, Artes y Tecnolog\u00eda","article_publisher":"https:\/\/www.facebook.com\/EscatUninter\/","article_published_time":"2020-01-22T01:40:13+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/wp-content\/uploads\/2020\/01\/1366_2000-1.jpg","type":"image\/jpeg"}],"author":"EquipoEscat","twitter_card":"summary_large_image","twitter_image":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/wp-content\/uploads\/2020\/01\/1366_2000-1.jpg","twitter_creator":"@EscatUninter","twitter_site":"@EscatUninter","twitter_misc":{"Escrito por":"EquipoEscat","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/intel-entrara-al-mundo-de-las-gpu-con-su-tarjeta-con-arquitectura-xe\/#article","isPartOf":{"@id":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/intel-entrara-al-mundo-de-las-gpu-con-su-tarjeta-con-arquitectura-xe\/"},"author":{"name":"EquipoEscat","@id":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/#\/schema\/person\/df7b8f33d62433cb78a2104bda02490d"},"headline":"Intel entrar\u00e1 al mundo de las GPU con su tarjeta con arquitectura Xe #ISC","datePublished":"2020-01-22T01:40:13+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/intel-entrara-al-mundo-de-las-gpu-con-su-tarjeta-con-arquitectura-xe\/"},"wordCount":327,"commentCount":0,"image":{"@id":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/intel-entrara-al-mundo-de-las-gpu-con-su-tarjeta-con-arquitectura-xe\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/wp-content\/uploads\/2020\/01\/1366_2000-1.jpg","keywords":["ESCAT","Ingenier\u00edas","Intel","Sistemas Computacionales","Uninter","Universidad Internacional"],"articleSection":["Certificaciones","CISCO","Ingenier\u00eda en Sistemas Computacionales","Ingenier\u00edas","Maestr\u00eda en Redes de Computadoras y Tecnolog\u00edas Web","Microsoft"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/intel-entrara-al-mundo-de-las-gpu-con-su-tarjeta-con-arquitectura-xe\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/intel-entrara-al-mundo-de-las-gpu-con-su-tarjeta-con-arquitectura-xe\/","url":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/intel-entrara-al-mundo-de-las-gpu-con-su-tarjeta-con-arquitectura-xe\/","name":"Intel entrar\u00e1 al mundo de las GPU con su tarjeta con arquitectura Xe","isPartOf":{"@id":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/intel-entrara-al-mundo-de-las-gpu-con-su-tarjeta-con-arquitectura-xe\/#primaryimage"},"image":{"@id":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/intel-entrara-al-mundo-de-las-gpu-con-su-tarjeta-con-arquitectura-xe\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/wp-content\/uploads\/2020\/01\/1366_2000-1.jpg","datePublished":"2020-01-22T01:40:13+00:00","author":{"@id":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/#\/schema\/person\/df7b8f33d62433cb78a2104bda02490d"},"description":"Los esfuerzos de Intel est\u00e1n centrados en el mercado de las CPU, pero esto podr\u00eda cambiar, pues han confirmado que trabajan en su primera GPU discreta.","breadcrumb":{"@id":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/intel-entrara-al-mundo-de-las-gpu-con-su-tarjeta-con-arquitectura-xe\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/intel-entrara-al-mundo-de-las-gpu-con-su-tarjeta-con-arquitectura-xe\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/intel-entrara-al-mundo-de-las-gpu-con-su-tarjeta-con-arquitectura-xe\/#primaryimage","url":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/wp-content\/uploads\/2020\/01\/1366_2000-1.jpg","contentUrl":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/wp-content\/uploads\/2020\/01\/1366_2000-1.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/intel-entrara-al-mundo-de-las-gpu-con-su-tarjeta-con-arquitectura-xe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/"},{"@type":"ListItem","position":2,"name":"Intel entrar\u00e1 al mundo de las GPU con su tarjeta con arquitectura Xe #ISC"}]},{"@type":"WebSite","@id":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/#website","url":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/","name":"Escuela de Ciencias, Artes y Tecnolog\u00eda UNINTER","description":"ESCAT","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/#\/schema\/person\/df7b8f33d62433cb78a2104bda02490d","name":"EquipoEscat","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d943e53cecc7e9e13c011abf6ec7475809c7d278834bde994b19ecd58034a9ff?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d943e53cecc7e9e13c011abf6ec7475809c7d278834bde994b19ecd58034a9ff?s=96&d=mm&r=g","caption":"EquipoEscat"},"url":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/author\/equipoescat\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/wp-content\/uploads\/2020\/01\/1366_2000-1.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/wp-json\/wp\/v2\/posts\/35572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/wp-json\/wp\/v2\/comments?post=35572"}],"version-history":[{"count":2,"href":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/wp-json\/wp\/v2\/posts\/35572\/revisions"}],"predecessor-version":[{"id":35730,"href":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/wp-json\/wp\/v2\/posts\/35572\/revisions\/35730"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/wp-json\/wp\/v2\/media\/35573"}],"wp:attachment":[{"href":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/wp-json\/wp\/v2\/media?parent=35572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/wp-json\/wp\/v2\/categories?post=35572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.uninter.edu.mx\/ESCAT\/index.php\/wp-json\/wp\/v2\/tags?post=35572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}